{"id":1534,"date":"2017-03-04T18:23:28","date_gmt":"2017-03-04T18:23:28","guid":{"rendered":"https:\/\/murcianoticias.es\/curiosidades\/?p=1534"},"modified":"2020-10-14T16:29:15","modified_gmt":"2020-10-14T16:29:15","slug":"enterate-de-las-ventajas-de-consumir-platano-para-tu-salud","status":"publish","type":"post","link":"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud","title":{"rendered":"Ent\u00e9rate de las ventajas de consumir pl\u00e1tano para tu salud"},"content":{"rendered":"<p style=\"text-align: justify\">El pl\u00e1tano es un bocado que no puede faltar en la dieta diaria de tu familia, adem\u00e1s de su incomparable sabor que lo hace ser la fruta preferida de los ni\u00f1os y su preciado valor nutritivo rico en potasio y az\u00facares, posee propiedades que lo convierten en un <strong>aliado clave para prevenir la proliferaci\u00f3n de c\u00e9lulas malignas en el cuerpo humano<\/strong>, reforzando el sistema inmunol\u00f3gico para luchar contra cualquier infecci\u00f3n y <strong>evitar la formaci\u00f3n de tumores que puedan originar un c\u00e1ncer.<\/strong><\/p>\n<h2 style=\"text-align: justify\">A continuaci\u00f3n mencionamos 7 beneficios que hacen del pl\u00e1tano un alimento ideal para tu salud:<\/h2>\n<h4 style=\"text-align: justify\">1. Combate la acidez<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1535\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-01.jpg\" alt=\"\" width=\"580\" height=\"327\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-01.jpg 800w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-01-300x169.jpg 300w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-01-768x433.jpg 768w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/p>\n<p style=\"text-align: justify\">La composici\u00f3n del pl\u00e1tano posee un pH muy elevado por lo que representa una soluci\u00f3n natural e inmediata para el malestar estomacal ocasionado por el reflujo g\u00e1strico, debe consumirse maduro para obtener mejores resultados.<\/p>\n<h4 style=\"text-align: justify\">2. Cuida tu coraz\u00f3n<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1536\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-02.jpg\" alt=\"\" width=\"580\" height=\"387\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-02.jpg 800w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-02-300x200.jpg 300w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-02-768x513.jpg 768w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/p>\n<p style=\"text-align: justify\">El alto contenido de potasio y fibra convierte al pl\u00e1tano en un excelente aliado para prevenir infartos al miocardio, regularizar la presi\u00f3n arterial y evitar accidentes cerebros vasculares.<\/p>\n<h4 style=\"text-align: justify\">3. Fuente de energ\u00eda<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1537\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-03.jpg\" alt=\"\" width=\"580\" height=\"388\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-03.jpg 800w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-03-300x201.jpg 300w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-03-768x514.jpg 768w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/p>\n<p style=\"text-align: justify\">Luego de una extenuante sesi\u00f3n de ejercicio nada mejor que consumir un pl\u00e1tano entero para reponer los minerales perdidos en el sudor y recuperar la fuerza y potencia muscular.<\/p>\n<h4 style=\"text-align: justify\">4. Cura la anemia<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1538\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-04.jpg\" alt=\"\" width=\"580\" height=\"435\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-04.jpg 800w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-04-300x225.jpg 300w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-04-768x576.jpg 768w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/p>\n<p style=\"text-align: justify\">La verdad es que el pl\u00e1tano es un tesoro m\u00e1s valioso que el oro para tu salud, posee un alto contenido de hierro que es el elemento que proporciona el color rojo en la sangre, por lo que induce la formaci\u00f3n de gl\u00f3bulos rojos en niveles \u00f3ptimos y por lo tanto erradica la anemia.<\/p>\n<h4 style=\"text-align: justify\">5. \u00dalceras<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1539\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-05.jpg\" alt=\"\" width=\"530\" height=\"548\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-05.jpg 636w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-05-290x300.jpg 290w\" sizes=\"(max-width: 530px) 100vw, 530px\" \/><\/p>\n<p style=\"text-align: justify\">Su alto contenido de almid\u00f3n proporciona alivio con respecto a los malestares estomacales ocasionado por la presencia de \u00falceras, adem\u00e1s previene el c\u00e1ncer de colon y estimula la digesti\u00f3n.<\/p>\n<h4 style=\"text-align: justify\">6. Levanta el \u00e1nimo<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1540\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-06.jpg\" alt=\"\" width=\"581\" height=\"387\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-06.jpg 800w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-06-300x200.jpg 300w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-06-768x512.jpg 768w\" sizes=\"(max-width: 581px) 100vw, 581px\" \/><\/p>\n<p style=\"text-align: justify\">Entre sus tanto nutrientes posee un elemento precursor de la hormona de la felicidad.<\/p>\n<h4 style=\"text-align: justify\">7. Proporciona relajaci\u00f3n<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1542\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-08.jpg\" alt=\"\" width=\"580\" height=\"811\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-08.jpg 732w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-08-214x300.jpg 214w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Se ha demostrado que el consumo de pl\u00e1tano es altamente beneficioso para el sistema nervioso, calma la ansiedad y es un elemento anti estr\u00e9s.<\/p>\n<p>\u00bfNecesitas m\u00e1s motivos para ingerir pl\u00e1tano? Disfruta este regalo de la naturaleza y comparte este art\u00edculo para que tus amigos tambi\u00e9n conozcan las bondades de esta fruta para la salud.<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1543\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-10.jpg\" alt=\"\" width=\"801\" height=\"536\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-10.jpg 800w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-10-300x201.jpg 300w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/Beneficios-del-platano-10-768x514.jpg 768w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pl\u00e1tano es un bocado que no puede faltar en la dieta diaria de tu familia, adem\u00e1s de su incomparable sabor que lo hace ser la fruta preferida de los ni\u00f1os y su preciado valor nutritivo rico en potasio y az\u00facares, posee propiedades que lo convierten en un aliado clave para prevenir la proliferaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,12],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ent\u00e9rate de las ventajas de consumir pl\u00e1tano para tu salud<\/title>\n<meta name=\"description\" content=\"El pl\u00e1tano es un bocado que no puede faltar en la dieta diaria de tu familia, adem\u00e1s de su incomparable sabor que lo hace ser la fruta preferida de los\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ent\u00e9rate de las ventajas de consumir pl\u00e1tano para tu salud\" \/>\n<meta property=\"og:description\" content=\"El pl\u00e1tano es un bocado que no puede faltar en la dieta diaria de tu familia, adem\u00e1s de su incomparable sabor que lo hace ser la fruta preferida de los\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud\" \/>\n<meta property=\"og:site_name\" content=\"Curiosidades y temas virales\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/curiosidadesTv1\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-04T18:23:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T16:29:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/los-beneficios-del-platano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"481\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"curioso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"curioso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud\",\"name\":\"Ent\u00e9rate de las ventajas de consumir pl\u00e1tano para tu salud\",\"isPartOf\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/los-beneficios-del-platano.jpg\",\"datePublished\":\"2017-03-04T18:23:28+00:00\",\"dateModified\":\"2020-10-14T16:29:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\"},\"description\":\"El pl\u00e1tano es un bocado que no puede faltar en la dieta diaria de tu familia, adem\u00e1s de su incomparable sabor que lo hace ser la fruta preferida de los\",\"breadcrumb\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud#primaryimage\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/los-beneficios-del-platano.jpg\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/los-beneficios-del-platano.jpg\",\"width\":920,\"height\":481},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ent\u00e9rate de las ventajas de consumir pl\u00e1tano para tu salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\",\"name\":\"Curiosidades y temas virales\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\",\"name\":\"curioso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"caption\":\"curioso\"},\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ent\u00e9rate de las ventajas de consumir pl\u00e1tano para tu salud","description":"El pl\u00e1tano es un bocado que no puede faltar en la dieta diaria de tu familia, adem\u00e1s de su incomparable sabor que lo hace ser la fruta preferida de los","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud","og_locale":"es_ES","og_type":"article","og_title":"Ent\u00e9rate de las ventajas de consumir pl\u00e1tano para tu salud","og_description":"El pl\u00e1tano es un bocado que no puede faltar en la dieta diaria de tu familia, adem\u00e1s de su incomparable sabor que lo hace ser la fruta preferida de los","og_url":"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud","og_site_name":"Curiosidades y temas virales","article_publisher":"https:\/\/www.facebook.com\/curiosidadesTv1","article_published_time":"2017-03-04T18:23:28+00:00","article_modified_time":"2020-10-14T16:29:15+00:00","og_image":[{"width":920,"height":481,"url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/los-beneficios-del-platano.jpg","type":"image\/jpeg"}],"author":"curioso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"curioso","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud","url":"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud","name":"Ent\u00e9rate de las ventajas de consumir pl\u00e1tano para tu salud","isPartOf":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud#primaryimage"},"image":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud#primaryimage"},"thumbnailUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/los-beneficios-del-platano.jpg","datePublished":"2017-03-04T18:23:28+00:00","dateModified":"2020-10-14T16:29:15+00:00","author":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961"},"description":"El pl\u00e1tano es un bocado que no puede faltar en la dieta diaria de tu familia, adem\u00e1s de su incomparable sabor que lo hace ser la fruta preferida de los","breadcrumb":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud#primaryimage","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/los-beneficios-del-platano.jpg","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2017\/03\/los-beneficios-del-platano.jpg","width":920,"height":481},{"@type":"BreadcrumbList","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/alimentacion\/enterate-de-las-ventajas-de-consumir-platano-para-tu-salud#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.murcianoticias.es\/curiosidades\/"},{"@type":"ListItem","position":2,"name":"Ent\u00e9rate de las ventajas de consumir pl\u00e1tano para tu salud"}]},{"@type":"WebSite","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website","url":"https:\/\/www.murcianoticias.es\/curiosidades\/","name":"Curiosidades y temas virales","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961","name":"curioso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","caption":"curioso"},"url":"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso"}]}},"_links":{"self":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/1534"}],"collection":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/comments?post=1534"}],"version-history":[{"count":0,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/1534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media\/1544"}],"wp:attachment":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media?parent=1534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/categories?post=1534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/tags?post=1534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}