{"id":218,"date":"2016-11-16T13:40:24","date_gmt":"2016-11-16T13:40:24","guid":{"rendered":"https:\/\/murcianoticias.es\/curiosidades\/?p=218"},"modified":"2020-10-11T22:38:42","modified_gmt":"2020-10-11T22:38:42","slug":"tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie","status":"publish","type":"post","link":"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie","title":{"rendered":"Tienes una protuberancia en la esquina del ojo: todo se debe a la especie"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>El cuerpo humano funciona de manera sorprendente, cuenta con herramientas que ni nosotros sab\u00edamos para que serv\u00edan.<\/strong> Los ojos representan una de las maravillas de la naturaleza, no solo por toda la gama de colores que existen que depende de los gustos llaman m\u00e1s la atenci\u00f3n, sino por un elemento que no hemos notado.<\/p>\n<p style=\"text-align: justify\"><strong>De seguro no te has percatado que los ojos cuentan con una protuberancia de color de la piel en la esquina interior del ojo.<\/strong> De hecho ah\u00ed es donde se acumulan las dichosas laga\u00f1as que nos fastidian tanto. Bueno, si piensas que eso solo est\u00e1 por estar, te equivocas ya que se debe a la evoluci\u00f3n de la especie.<\/p>\n<p style=\"text-align: justify\"><!--nextpage--><\/p>\n<p style=\"text-align: justify\">Si te fijas bien ese bultico se divide en dos partes que se diferencian bastante bien. Por un lado se le llama car\u00fancula lacrimal y el por otro se le puede llamar media luna, esta se encarga de envolver el globo ocular.<\/p>\n<p style=\"text-align: justify\">Por muchos siglos los cient\u00edficos y los m\u00e9dicos no llegaban a una conclusi\u00f3n sobre el significado de dichas formaciones tan particulares; no obstante, hace poco dieron con lo que se cree es la soluci\u00f3n.<\/p>\n<p style=\"text-align: justify\"><!--nextpage--><\/p>\n<p style=\"text-align: justify\"><strong>Bueno, cuando se habla de media luna se piensa que es un recuerdo del parpado que cubrir\u00e1 anteriormente los ojos<\/strong>, siendo que el parpado que tenemos actualmente era como el de las aves y reptiles, pero por la evoluci\u00f3n ha desaparecido casi todo.<\/p>\n<p style=\"text-align: justify\">Esta dichosa membrana la tienen los animales para protegerse de los agentes externos de las naturales, es decir, son como una especie de lentes de sol que los ayuda a protegerse. Se puede decir que la teor\u00eda m\u00e1s aceptada es la de la evoluci\u00f3n de la especie.<\/p>\n<p style=\"text-align: justify\"><!--nextpage--><\/p>\n<p style=\"text-align: justify\"><strong>Muchos expertos tambi\u00e9n han realizado otras teor\u00edas de que esta membrana en realidad proviene de criaturas acu\u00e1ticas<\/strong> que contaban con la membrana denominada nictitante. El punto es que el humano seguir\u00e1 evolucionando para adaptarse a la naturaleza de la tierra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cuerpo humano funciona de manera sorprendente, cuenta con herramientas que ni nosotros sab\u00edamos para que serv\u00edan. Los ojos representan una de las maravillas de la naturaleza, no solo por toda la gama de colores que existen que depende de los gustos llaman m\u00e1s la atenci\u00f3n, sino por un elemento que no hemos notado. De [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tienes una protuberancia en la esquina del ojo: todo se debe a la especie<\/title>\n<meta name=\"description\" content=\"El cuerpo humano funciona de manera sorprendente, cuenta con herramientas que ni nosotros sab\u00edamos para que serv\u00edan. Los ojos representan una de las\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie\" \/>\n<link rel=\"next\" href=\"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie\/2\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tienes una protuberancia en la esquina del ojo: todo se debe a la especie\" \/>\n<meta property=\"og:description\" content=\"El cuerpo humano funciona de manera sorprendente, cuenta con herramientas que ni nosotros sab\u00edamos para que serv\u00edan. Los ojos representan una de las\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie\" \/>\n<meta property=\"og:site_name\" content=\"Curiosidades y temas virales\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/curiosidadesTv1\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-16T13:40:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-11T22:38:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2016\/11\/Tienes-una-protuberancia-en-la-esquina-del-ojo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"206\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"curioso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"curioso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie\",\"name\":\"Tienes una protuberancia en la esquina del ojo: todo se debe a la especie\",\"isPartOf\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2016\/11\/Tienes-una-protuberancia-en-la-esquina-del-ojo.jpg\",\"datePublished\":\"2016-11-16T13:40:24+00:00\",\"dateModified\":\"2020-10-11T22:38:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\"},\"description\":\"El cuerpo humano funciona de manera sorprendente, cuenta con herramientas que ni nosotros sab\u00edamos para que serv\u00edan. Los ojos representan una de las\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie#primaryimage\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2016\/11\/Tienes-una-protuberancia-en-la-esquina-del-ojo.jpg\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2016\/11\/Tienes-una-protuberancia-en-la-esquina-del-ojo.jpg\",\"width\":600,\"height\":206},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\",\"name\":\"Curiosidades y temas virales\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\",\"name\":\"curioso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"caption\":\"curioso\"},\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tienes una protuberancia en la esquina del ojo: todo se debe a la especie","description":"El cuerpo humano funciona de manera sorprendente, cuenta con herramientas que ni nosotros sab\u00edamos para que serv\u00edan. Los ojos representan una de las","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie","next":"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie\/2","og_locale":"es_ES","og_type":"article","og_title":"Tienes una protuberancia en la esquina del ojo: todo se debe a la especie","og_description":"El cuerpo humano funciona de manera sorprendente, cuenta con herramientas que ni nosotros sab\u00edamos para que serv\u00edan. Los ojos representan una de las","og_url":"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie","og_site_name":"Curiosidades y temas virales","article_publisher":"https:\/\/www.facebook.com\/curiosidadesTv1","article_published_time":"2016-11-16T13:40:24+00:00","article_modified_time":"2020-10-11T22:38:42+00:00","og_image":[{"width":600,"height":206,"url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2016\/11\/Tienes-una-protuberancia-en-la-esquina-del-ojo.jpg","type":"image\/jpeg"}],"author":"curioso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"curioso","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie","url":"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie","name":"Tienes una protuberancia en la esquina del ojo: todo se debe a la especie","isPartOf":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie#primaryimage"},"image":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie#primaryimage"},"thumbnailUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2016\/11\/Tienes-una-protuberancia-en-la-esquina-del-ojo.jpg","datePublished":"2016-11-16T13:40:24+00:00","dateModified":"2020-10-11T22:38:42+00:00","author":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961"},"description":"El cuerpo humano funciona de manera sorprendente, cuenta con herramientas que ni nosotros sab\u00edamos para que serv\u00edan. Los ojos representan una de las","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/salud-y-belleza\/tienes-una-protuberancia-en-la-esquina-del-ojo-todo-se-debe-la-especie#primaryimage","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2016\/11\/Tienes-una-protuberancia-en-la-esquina-del-ojo.jpg","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2016\/11\/Tienes-una-protuberancia-en-la-esquina-del-ojo.jpg","width":600,"height":206},{"@type":"WebSite","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website","url":"https:\/\/www.murcianoticias.es\/curiosidades\/","name":"Curiosidades y temas virales","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961","name":"curioso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","caption":"curioso"},"url":"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso"}]}},"_links":{"self":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/218"}],"collection":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/comments?post=218"}],"version-history":[{"count":0,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media\/219"}],"wp:attachment":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media?parent=218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/categories?post=218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/tags?post=218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}