{"id":2435,"date":"2019-04-25T18:38:12","date_gmt":"2019-04-25T18:38:12","guid":{"rendered":"https:\/\/murcianoticias.es\/curiosidades\/?p=2435"},"modified":"2020-10-09T01:45:23","modified_gmt":"2020-10-09T01:45:23","slug":"mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante","status":"publish","type":"post","link":"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante","title":{"rendered":"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante."},"content":{"rendered":"<h3>Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante.<\/h3>\n<p>aunque muchos le temen, el \u00e1rea sigue siendo estad\u00edsticamente uno de los veh\u00edculos m\u00e1s seguros: causa 0,006 muertes cada a\u00f1o, en comparaci\u00f3n con docenas de autom\u00f3viles y cientos de motocicletas. Esto no significa que no pueda haber m\u00e1s o menos accidentes graves en el avi\u00f3n, en los que hay que saber c\u00f3mo comportarse. Este es el prop\u00f3sito de las introducciones que los operadores de vuelos hacen antes de cada despegue, pero seg\u00fan lo que sucedi\u00f3 hace unos d\u00edas en un vuelo regular de EE.UU., no parecen ser suficientes o tal vez no sean suficientes y la atenci\u00f3n y seriedad de los pasajeros.<\/p>\n<p>El vuelo de Nueva York a Dallas tuvo que hacer un aterrizaje de emergencia tras la explosi\u00f3n de uno de los motores, que provoc\u00f3 la fractura de una ventana.<\/p>\n<p>El experto en vuelo Bobby Laurie destac\u00f3 el detalle en un post de Twitter: al hacerlo, los pasajeros no est\u00e1n recibiendo suficiente ox\u00edgeno para evitar las consecuencias descritas anteriormente de una deficiencia de ox\u00edgeno.<\/p>\n<p>Y tambi\u00e9n, como lo exigen las regulaciones de todas las aerol\u00edneas, antes de despegar los operadores han explicado c\u00f3mo utilizar las m\u00e1scaras que, en aras de la exhaustividad, presentamos a continuaci\u00f3n.<\/p>\n<p>Si es necesario, las m\u00e1scaras de ox\u00edgeno caer\u00e1n del compartimiento por encima de la cabeza. Para activar el flujo de ox\u00edgeno, tire hacia abajo de la mascarilla hasta que el tubo de pl\u00e1stico est\u00e9 completamente extendido. Coloque la mascarilla sobre la nariz y la boca y respire normalmente.<br \/>\nAsegure la mascarilla con la cinta el\u00e1stica. Aunque el ox\u00edgeno fluya, es posible que la bolsa de pl\u00e1stico no se hinche. Contin\u00fae usando la m\u00e1scara hasta que un miembro de la tripulaci\u00f3n le notifique lo contrario. Si viaja con ni\u00f1os o alguien que necesita asistencia especial, use primero la m\u00e1scara para ni\u00f1os.<br \/>\nDesgraciadamente, es com\u00fan no prestar demasiada atenci\u00f3n a lo que se dice antes del vuelo, confiando en que todo ir\u00e1 bien y que no habr\u00e1 necesidad de dispositivos de seguridad: esto significa, sin embargo, confiar en la certeza de que nadie podr\u00e1 darle jam\u00e1s, ni siquiera el medio de transporte m\u00e1s seguro del mundo.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/aVRLXzaKCtI\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante. aunque muchos le temen, el \u00e1rea sigue siendo estad\u00edsticamente uno de los veh\u00edculos m\u00e1s seguros: causa 0,006 muertes cada a\u00f1o, en comparaci\u00f3n con docenas de autom\u00f3viles y cientos de motocicletas. Esto no significa que no pueda haber m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2436,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante.<\/title>\n<meta name=\"description\" content=\"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante. aunque muchos le temen, el \u00e1rea sigue siendo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante.\" \/>\n<meta property=\"og:description\" content=\"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante. aunque muchos le temen, el \u00e1rea sigue siendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante\" \/>\n<meta property=\"og:site_name\" content=\"Curiosidades y temas virales\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/curiosidadesTv1\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-25T18:38:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-09T01:45:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/avion-tubina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"curioso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"curioso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante\",\"name\":\"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante.\",\"isPartOf\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/avion-tubina.jpg\",\"datePublished\":\"2019-04-25T18:38:12+00:00\",\"dateModified\":\"2020-10-09T01:45:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\"},\"description\":\"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante. aunque muchos le temen, el \u00e1rea sigue siendo\",\"breadcrumb\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante#primaryimage\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/avion-tubina.jpg\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/avion-tubina.jpg\",\"width\":1280,\"height\":960,\"caption\":\"El vuelo de Nueva York a Dallas tuvo que hacer un aterrizaje de emergencia tras la explosi\u00f3n de uno de los motores, que provoc\u00f3 la fractura de una ventana.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\",\"name\":\"Curiosidades y temas virales\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\",\"name\":\"curioso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"caption\":\"curioso\"},\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante.","description":"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante. aunque muchos le temen, el \u00e1rea sigue siendo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante","og_locale":"es_ES","og_type":"article","og_title":"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante.","og_description":"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante. aunque muchos le temen, el \u00e1rea sigue siendo","og_url":"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante","og_site_name":"Curiosidades y temas virales","article_publisher":"https:\/\/www.facebook.com\/curiosidadesTv1","article_published_time":"2019-04-25T18:38:12+00:00","article_modified_time":"2020-10-09T01:45:23+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/avion-tubina.jpg","type":"image\/jpeg"}],"author":"curioso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"curioso","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante","url":"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante","name":"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante.","isPartOf":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante#primaryimage"},"image":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante#primaryimage"},"thumbnailUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/avion-tubina.jpg","datePublished":"2019-04-25T18:38:12+00:00","dateModified":"2020-10-09T01:45:23+00:00","author":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961"},"description":"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante. aunque muchos le temen, el \u00e1rea sigue siendo","breadcrumb":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante#primaryimage","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/avion-tubina.jpg","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/avion-tubina.jpg","width":1280,"height":960,"caption":"El vuelo de Nueva York a Dallas tuvo que hacer un aterrizaje de emergencia tras la explosi\u00f3n de uno de los motores, que provoc\u00f3 la fractura de una ventana."},{"@type":"BreadcrumbList","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/increible\/mucha-gente-ha-visto-esta-foto-en-los-ultimos-dias-pero-nadie-ha-notado-un-detalle-importante#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.murcianoticias.es\/curiosidades\/"},{"@type":"ListItem","position":2,"name":"Mucha gente ha visto esta foto en los \u00faltimos d\u00edas, pero nadie ha notado un detalle importante."}]},{"@type":"WebSite","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website","url":"https:\/\/www.murcianoticias.es\/curiosidades\/","name":"Curiosidades y temas virales","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961","name":"curioso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","caption":"curioso"},"url":"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso"}]}},"_links":{"self":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2435"}],"collection":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/comments?post=2435"}],"version-history":[{"count":0,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media\/2436"}],"wp:attachment":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media?parent=2435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/categories?post=2435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/tags?post=2435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}