{"id":2548,"date":"2019-04-29T17:01:51","date_gmt":"2019-04-29T17:01:51","guid":{"rendered":"https:\/\/murcianoticias.es\/curiosidades\/?p=2548"},"modified":"2020-10-02T16:13:31","modified_gmt":"2020-10-02T16:13:31","slug":"leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas","status":"publish","type":"post","link":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas","title":{"rendered":"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas"},"content":{"rendered":"<h3>Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas<\/h3>\n<p>distribuido por Koch Media a trav\u00e9s de su sello Midnight Factory, La casa de la mu\u00f1eca es la pel\u00edcula de terror dirigida por Pascal Laugier, autor de Martyrs and I bambini di Cold Rock.<br \/>\nComo sugiere el t\u00edtulo, las mu\u00f1ecas son uno de los elementos m\u00e1s perturbadores del largometraje, como cuando, tal vez, en la escuela le dijimos a nuestro compa\u00f1ero m\u00e1s ingenuo o cr\u00e9dulo que pod\u00edan volver para vengarse de \u00e9l en caso de que los abandonara en la basura, cansados de mantenerlos en casa.<br \/>\nPero, \u00bfcu\u00e1ntas leyendas o historias inquietantes hemos escuchado sobre las mu\u00f1ecas, especialmente hoy en d\u00eda que, en el tercer milenio en curso, el fen\u00f3meno de la creepypasta est\u00e1 muy extendido en Internet?<br \/>\nVamos a descubrir algunos de ellos.<\/p>\n<h3>La misteriosa Sara (y no s\u00f3lo)<\/h3>\n<p>Navegando a diario por la densa e insidiosa selva de la red, son muchas las historias que, caracterizadas por un ambiente general capaz de mantenerlas en constante equilibrio entre realidad y ficci\u00f3n, transmiten sensaciones de horror y miedo al poner en juego, precisamente, estos inocentes juguetes infantiles.<br \/>\nVan desde la mu\u00f1eca que perteneci\u00f3 a su abuela, considerada de Satan\u00e1s y probablemente responsable de la muerte de los padres del narrador, con una descripci\u00f3n de los pulmones y \u00f3rganos esparcidos por el suelo, hasta la figura de la peque\u00f1a Sara, que deambula por las calles con una marioneta rota y con la que ciertamente es aconsejable no hablar.<br \/>\nPor no hablar de la mu\u00f1eca de cer\u00e1mica que se encuentra en una acera de Singapur y que, vestida con un vestido antiguo y con los ojos vendados, los lugare\u00f1os est\u00e1n convencidos de que est\u00e1 maldita.<\/p>\n<h3>\u00bfQui\u00e9n le teme a la Isla de las Mu\u00f1ecas?<\/h3>\n<p>Aunque, sin duda, entre las muchas historias que abarrotan la red, una de las m\u00e1s conocidas es la de la llamada Isla de las Mu\u00f1ecas, ubicada en los canales al sur de la Ciudad de M\u00e9xico.<br \/>\nAhora es una atracci\u00f3n tur\u00edstica, es una isla caracterizada por un fondo \u00fanico: hace a\u00f1os, el \u00fanico habitante local encontr\u00f3 en el agua el cuerpo de un ni\u00f1o flotante, desgraciadamente desaparecido demasiado pronto, y luego tambi\u00e9n encontr\u00f3 una mu\u00f1eca que decidi\u00f3 colgarse de un \u00e1rbol para complacer el esp\u00edritu del peque\u00f1o difunto, a quien se dedica el lugar.<br \/>\nEl hombre cre\u00eda que la isla estaba infestada por su esp\u00edritu, as\u00ed que para hacerla feliz y mantener el mal a raya, comenz\u00f3 a colgar mu\u00f1ecas de cada \u00e1rbol.<br \/>\nComo resultado, hoy en d\u00eda la isla es el hogar de cientos de mu\u00f1ecas mutiladas que adornan \u00e1rboles y otras superficies, y muchos dicen haberlas escuchado susurrando entre ellos mientras caminaban por la zona.<\/p>\n<h3>\u00bfSon s\u00f3lo juegos de ni\u00f1os?<\/h3>\n<p>M\u00e1s bien espantoso es tambi\u00e9n la mala aventura emprendida por el joven Steve y Clarke en busca de su amigo Gabriel en la casa de mu\u00f1ecas oscura, de la que le dejamos adivinar que es cualquier cosa menos una final satisfactoria.<br \/>\nLuego est\u00e1n los que hablan de un curioso juego factible con mechones de pelo para quemar y cinco mu\u00f1ecas de porcelana, m\u00e1s una para sacrificar que debe ser dividida en seis piezas en un lugar abandonado, donde luego vendr\u00e1n los dem\u00e1s a buscarte para encontrar la cabeza de su pareja y reconstruirla, parte tras parte.<br \/>\n\u00bfY qu\u00e9 hay de la leyenda seg\u00fan la cual, en Illinois, cada vez que una madre da a luz a un ni\u00f1o, una mu\u00f1eca comienza a llorar continuamente, al mismo tiempo que \u00e9l, deteni\u00e9ndose s\u00f3lo cuando se le rompe la cabeza, pero con consecuencias terribles e inesperadas para el ni\u00f1o?<\/p>\n<h3>Creadores de horror<\/h3>\n<p>Partiendo de la historia del marido que, con mu\u00f1ecas en la casa donde vive con su mujer, nos empuja a comprender el secreto de esos t\u00edteres cuando sus ojos comienzan a explotar en montones de larvas, parece que uno de los temas m\u00e1s populares de estas historias es, sin embargo, el del fabricante decididamente fuera de s\u00ed.<br \/>\nEn la pila, de hecho, tenemos al cirujano de Europa del Este dedicado a transformar a las ni\u00f1as en juguetes sexuales f\u00e1ciles de manejar, as\u00ed como al fabricante de mu\u00f1ecas que s\u00f3lo tienes que adivinar d\u00f3nde encuentras los ojos de su nueva criatura.<br \/>\nPero tambi\u00e9n est\u00e1 la joven Viky, que, ocupada todo el d\u00eda viendo pel\u00edculas de terror, su gran pasi\u00f3n, se encuentra en una casa vieja, donde termina transformada en una mu\u00f1eca vud\u00fa&#8230; con una descripci\u00f3n detallada y macabra del trato atroz que se le ha reservado.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/brjhVjts4SA\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas distribuido por Koch Media a trav\u00e9s de su sello Midnight Factory, La casa de la mu\u00f1eca es la pel\u00edcula de terror dirigida por Pascal Laugier, autor de Martyrs and I bambini di Cold Rock. Como sugiere el t\u00edtulo, las mu\u00f1ecas son uno de los elementos m\u00e1s perturbadores [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2549,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[976],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas<\/title>\n<meta name=\"description\" content=\"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas distribuido por Koch Media a trav\u00e9s de su sello Midnight Factory, La casa de la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas\" \/>\n<meta property=\"og:description\" content=\"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas distribuido por Koch Media a trav\u00e9s de su sello Midnight Factory, La casa de la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas\" \/>\n<meta property=\"og:site_name\" content=\"Curiosidades y temas virales\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/curiosidadesTv1\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-29T17:01:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-02T16:13:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/mu\u00f1ecas-de-terror.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1936\" \/>\n\t<meta property=\"og:image:height\" content=\"2592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"curioso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"curioso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas\",\"name\":\"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas\",\"isPartOf\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/mu\u00f1ecas-de-terror.jpg\",\"datePublished\":\"2019-04-29T17:01:51+00:00\",\"dateModified\":\"2020-10-02T16:13:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\"},\"description\":\"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas distribuido por Koch Media a trav\u00e9s de su sello Midnight Factory, La casa de la\",\"breadcrumb\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas#primaryimage\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/mu\u00f1ecas-de-terror.jpg\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/mu\u00f1ecas-de-terror.jpg\",\"width\":1936,\"height\":2592,\"caption\":\"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\",\"name\":\"Curiosidades y temas virales\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\",\"name\":\"curioso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"caption\":\"curioso\"},\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas","description":"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas distribuido por Koch Media a trav\u00e9s de su sello Midnight Factory, La casa de la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas","og_locale":"es_ES","og_type":"article","og_title":"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas","og_description":"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas distribuido por Koch Media a trav\u00e9s de su sello Midnight Factory, La casa de la","og_url":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas","og_site_name":"Curiosidades y temas virales","article_publisher":"https:\/\/www.facebook.com\/curiosidadesTv1","article_published_time":"2019-04-29T17:01:51+00:00","article_modified_time":"2020-10-02T16:13:31+00:00","og_image":[{"width":1936,"height":2592,"url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/mu\u00f1ecas-de-terror.jpg","type":"image\/jpeg"}],"author":"curioso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"curioso","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas","url":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas","name":"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas","isPartOf":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas#primaryimage"},"image":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas#primaryimage"},"thumbnailUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/mu\u00f1ecas-de-terror.jpg","datePublished":"2019-04-29T17:01:51+00:00","dateModified":"2020-10-02T16:13:31+00:00","author":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961"},"description":"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas distribuido por Koch Media a trav\u00e9s de su sello Midnight Factory, La casa de la","breadcrumb":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas#primaryimage","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/mu\u00f1ecas-de-terror.jpg","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/04\/mu\u00f1ecas-de-terror.jpg","width":1936,"height":2592,"caption":"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/leyendas-espeluznantes-y-curiosidades-inquietantes-sobre-las-munecas#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.murcianoticias.es\/curiosidades\/"},{"@type":"ListItem","position":2,"name":"Leyendas, espeluznantes y curiosidades inquietantes sobre las mu\u00f1ecas"}]},{"@type":"WebSite","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website","url":"https:\/\/www.murcianoticias.es\/curiosidades\/","name":"Curiosidades y temas virales","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961","name":"curioso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","caption":"curioso"},"url":"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso"}]}},"_links":{"self":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2548"}],"collection":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/comments?post=2548"}],"version-history":[{"count":0,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media\/2549"}],"wp:attachment":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media?parent=2548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/categories?post=2548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/tags?post=2548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}