{"id":2674,"date":"2019-05-02T23:14:27","date_gmt":"2019-05-02T23:14:27","guid":{"rendered":"https:\/\/murcianoticias.es\/curiosidades\/?p=2674"},"modified":"2020-10-11T06:28:21","modified_gmt":"2020-10-11T06:28:21","slug":"3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo","status":"publish","type":"post","link":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo","title":{"rendered":"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!"},"content":{"rendered":"<h3>3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!<\/h3>\n<h3>Historias de terror reales: Tres golpes a la puerta en medio de la noche<\/h3>\n<p>Un tipo sol\u00eda ver \u00abThe Walking Dead\u00bb con su abuela. Una noche se levantaron tarde, casi hasta las 4:00 a.m., cuando decidieron irse a la cama. El ni\u00f1o fue al ba\u00f1o a lavarse los dientes y, mientras el agua flu\u00eda, sinti\u00f3 tres golpes en la puerta. Pensando que era su abuela la que quer\u00eda saber si estaba en el ba\u00f1o, dijo que s\u00ed, pero no respondi\u00f3. Cuando se fue, su abuela le pregunt\u00f3 qu\u00e9 quer\u00eda: tambi\u00e9n hab\u00eda o\u00eddo tres golpes en su puerta. Los dos, aterrorizados, exploraron la casa en busca de la persona que podr\u00eda haber llamado a la puerta. Sin embargo, no hab\u00eda nadie all\u00ed. Lo m\u00e1s inquietante es que su abuela hab\u00eda perdido a un hijo cuando era peque\u00f1a y otro hab\u00eda estado desaparecido durante mucho tiempo. Quiz\u00e1s ambos hab\u00edan intentado ser recordados.<\/p>\n<h3>Cuentos del miedo: Escalofr\u00edos en la casa de retiro<\/h3>\n<p>Una enfermera trabajaba en un hospicio especializado en pacientes con Alzheimer. Su trabajo principal era cuidar a los pacientes y lavar los platos. Una noche, mientras recog\u00eda los platos sucios, sinti\u00f3 que alguien la segu\u00eda. Asustada, entr\u00f3 en el ba\u00f1o y espiando por la puerta se dio cuenta de que era una de las pacientes: al principio se cri\u00f3 y pronto se dio cuenta de que era un anciano que hab\u00eda muerto tres d\u00edas antes. Pocos d\u00edas despu\u00e9s escuch\u00f3 a alguien susurrando al o\u00eddo, aunque la habitaci\u00f3n en la que estaba estaba estaba completamente vac\u00eda: concentrada, record\u00f3 que era la voz de su abuela, que hab\u00eda estado muerta durante mucho tiempo.<\/p>\n<h3>Historias de horror: La cisterna infernal<\/h3>\n<p>La verdadera historia de Elisa Lam es realmente aterradora, se lo podemos asegurar. La chica desapareci\u00f3 en el aire cuando estaba en un hotel en Los \u00c1ngeles. La polic\u00eda trat\u00f3 de encontrarla, pero todo lo que pudo encontrar fue un video de seguridad en el que se la ve\u00eda hablando con alguien en un ascensor, a pesar de que estaba vac\u00edo. Cuando la puerta se abri\u00f3 de repente, Elisa escap\u00f3 en una crisis de p\u00e1nico. Los hu\u00e9spedes del hotel comenzaron a ver un l\u00edquido negro que sal\u00eda de los grifos, algo que la administraci\u00f3n del hotel sospechaba. Finalmente, el cuerpo de la ni\u00f1a fue encontrado en la cisterna, que estaba cerrada por fuera con un candado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo! Historias de terror reales: Tres golpes a la puerta en medio de la noche Un tipo sol\u00eda ver \u00abThe Walking Dead\u00bb con su abuela. Una noche se levantaron tarde, casi hasta las 4:00 a.m., cuando decidieron irse a la cama. El ni\u00f1o fue al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[976],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!<\/title>\n<meta name=\"description\" content=\"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo! Historias de terror reales: Tres golpes a la puerta en medio de la noche Un tipo sol\u00eda ver &quot;The\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!\" \/>\n<meta property=\"og:description\" content=\"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo! Historias de terror reales: Tres golpes a la puerta en medio de la noche Un tipo sol\u00eda ver &quot;The\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo\" \/>\n<meta property=\"og:site_name\" content=\"Curiosidades y temas virales\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/curiosidadesTv1\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-02T23:14:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-11T06:28:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/foto-escaloriante.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"curioso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"curioso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo\",\"name\":\"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!\",\"isPartOf\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/foto-escaloriante.jpeg\",\"datePublished\":\"2019-05-02T23:14:27+00:00\",\"dateModified\":\"2020-10-11T06:28:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\"},\"description\":\"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo! Historias de terror reales: Tres golpes a la puerta en medio de la noche Un tipo sol\u00eda ver \\\"The\",\"breadcrumb\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo#primaryimage\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/foto-escaloriante.jpeg\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/foto-escaloriante.jpeg\",\"width\":1024,\"height\":1024,\"caption\":\"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\",\"name\":\"Curiosidades y temas virales\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\",\"name\":\"curioso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"caption\":\"curioso\"},\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!","description":"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo! Historias de terror reales: Tres golpes a la puerta en medio de la noche Un tipo sol\u00eda ver \"The","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo","og_locale":"es_ES","og_type":"article","og_title":"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!","og_description":"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo! Historias de terror reales: Tres golpes a la puerta en medio de la noche Un tipo sol\u00eda ver \"The","og_url":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo","og_site_name":"Curiosidades y temas virales","article_publisher":"https:\/\/www.facebook.com\/curiosidadesTv1","article_published_time":"2019-05-02T23:14:27+00:00","article_modified_time":"2020-10-11T06:28:21+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/foto-escaloriante.jpeg","type":"image\/jpeg"}],"author":"curioso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"curioso","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo","url":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo","name":"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!","isPartOf":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo#primaryimage"},"image":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo#primaryimage"},"thumbnailUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/foto-escaloriante.jpeg","datePublished":"2019-05-02T23:14:27+00:00","dateModified":"2020-10-11T06:28:21+00:00","author":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961"},"description":"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo! Historias de terror reales: Tres golpes a la puerta en medio de la noche Un tipo sol\u00eda ver \"The","breadcrumb":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo#primaryimage","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/foto-escaloriante.jpeg","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/foto-escaloriante.jpeg","width":1024,"height":1024,"caption":"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!"},{"@type":"BreadcrumbList","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/terror\/3-cuentos-de-terror-que-nunca-te-dejaran-dormir-de-nuevo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.murcianoticias.es\/curiosidades\/"},{"@type":"ListItem","position":2,"name":"3 Cuentos de terror que nunca te dejar\u00e1n dormir de nuevo!"}]},{"@type":"WebSite","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website","url":"https:\/\/www.murcianoticias.es\/curiosidades\/","name":"Curiosidades y temas virales","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961","name":"curioso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","caption":"curioso"},"url":"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso"}]}},"_links":{"self":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2674"}],"collection":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/comments?post=2674"}],"version-history":[{"count":0,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media\/2675"}],"wp:attachment":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media?parent=2674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/categories?post=2674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/tags?post=2674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}