{"id":2745,"date":"2019-05-05T20:49:12","date_gmt":"2019-05-05T20:49:12","guid":{"rendered":"https:\/\/murcianoticias.es\/curiosidades\/?p=2745"},"modified":"2020-10-14T23:31:34","modified_gmt":"2020-10-14T23:31:34","slug":"cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia","status":"publish","type":"post","link":"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia","title":{"rendered":"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia."},"content":{"rendered":"<h3>Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia.<\/h3>\n<p>Los huracanes y las decisiones pol\u00edticas que ponen en peligro la unidad de muchas familias inmigrantes en Estados Unidos no son suficientes para frenar el profundo sentido de solidaridad que caracteriza a los ciudadanos de este pa\u00eds, golpeado en dos semanas no por uno sino por dos huracanes, Harvey e Irma.<br \/>\nAyudar a todas las personas en dificultad requiere enormes esfuerzos, porque las cifras son enormes, pero la ayuda b\u00e1sica siempre viene de abajo, del sentido de generosidad que muchos han demostrado en esos d\u00edas dif\u00edciles. Un ejemplo de esto es el trabajo realizado por los due\u00f1os de un restaurante en Port Arthur, Texas, quienes, solos, prepararon m\u00e1s de mil comidas calientes sin costo alguno.<\/p>\n<p><img decoding=\"async\" class=\"mb5 sharemeagain\" src=\"https:\/\/img.wtvideo.com\/images\/article\/list\/14609_2.jpg\" \/><\/p>\n<div class=\"social\"><\/div>\n<p>En el restaurante Sake&amp;Sushi en este municipio de Texas, todo el personal se moviliz\u00f3 para ayudar a los afectados por el hurac\u00e1n Harvey.<\/p>\n<p>En un post compartido por el hijo de uno de los propietarios leemos:<\/p>\n<p>\u00abMi padre Phe y mi t\u00edo Binh tienen un restaurante en el sureste de Texas y tambi\u00e9n han sido golpeados por el hurac\u00e1n Harvey. Los peri\u00f3dicos no lo mencionaron, pero hoy ellos, todo el personal y muchos voluntarios cocinaron m\u00e1s de mil comidas calientes para ser entregadas a las v\u00edctimas, a los primeros auxilios y a otros voluntarios. Mi padre y mi t\u00edo son dos personas muy humildes, pero creo que vali\u00f3 la pena contar lo que hicieron. Si alguna vez se encuentra en el \u00e1rea de Port Arthur, pase por su restaurante y apoye a estos dos grandes trabajadores. Se lo merecen.<\/p>\n<p><img decoding=\"async\" class=\"mb5 sharemeagain\" src=\"https:\/\/img.wtvideo.com\/images\/article\/list\/14609_3.jpg\" \/><\/p>\n<div class=\"social\"><\/div>\n<p>Para preparar estas comidas con arroz, verduras y pollo, todo el personal del restaurante trabaj\u00f3 incansablemente durante todo el d\u00eda y la noche.<\/p>\n<p>El post del ni\u00f1o en Facebook recibi\u00f3 miles de comentarios positivos (\u00a1en muchos idiomas diferentes!) y se convirti\u00f3 en viral.<br \/>\nUna prueba m\u00e1s de que, a pesar de sus innumerables contradicciones, el sentimiento de pertenencia a este pa\u00eds es un elemento fuerte en todos los grupos \u00e9tnicos que lo componen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia. Los huracanes y las decisiones pol\u00edticas que ponen en peligro la unidad de muchas familias inmigrantes en Estados Unidos no son suficientes para frenar el profundo sentido de solidaridad que caracteriza a los ciudadanos de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia.<\/title>\n<meta name=\"description\" content=\"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia. Los huracanes y las decisiones\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia.\" \/>\n<meta property=\"og:description\" content=\"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia. Los huracanes y las decisiones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia\" \/>\n<meta property=\"og:site_name\" content=\"Curiosidades y temas virales\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/curiosidadesTv1\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-05T20:49:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T23:31:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/katrina_goes12_big.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1919\" \/>\n\t<meta property=\"og:image:height\" content=\"1198\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"curioso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"curioso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia\",\"name\":\"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia.\",\"isPartOf\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/katrina_goes12_big.jpg\",\"datePublished\":\"2019-05-05T20:49:12+00:00\",\"dateModified\":\"2020-10-14T23:31:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\"},\"description\":\"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia. Los huracanes y las decisiones\",\"breadcrumb\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia#primaryimage\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/katrina_goes12_big.jpg\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/katrina_goes12_big.jpg\",\"width\":1919,\"height\":1198,\"caption\":\"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\",\"name\":\"Curiosidades y temas virales\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\",\"name\":\"curioso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"caption\":\"curioso\"},\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia.","description":"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia. Los huracanes y las decisiones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia","og_locale":"es_ES","og_type":"article","og_title":"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia.","og_description":"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia. Los huracanes y las decisiones","og_url":"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia","og_site_name":"Curiosidades y temas virales","article_publisher":"https:\/\/www.facebook.com\/curiosidadesTv1","article_published_time":"2019-05-05T20:49:12+00:00","article_modified_time":"2020-10-14T23:31:34+00:00","og_image":[{"width":1919,"height":1198,"url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/katrina_goes12_big.jpg","type":"image\/jpeg"}],"author":"curioso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"curioso","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia","url":"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia","name":"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia.","isPartOf":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia#primaryimage"},"image":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia#primaryimage"},"thumbnailUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/katrina_goes12_big.jpg","datePublished":"2019-05-05T20:49:12+00:00","dateModified":"2020-10-14T23:31:34+00:00","author":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961"},"description":"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia. Los huracanes y las decisiones","breadcrumb":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia#primaryimage","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/katrina_goes12_big.jpg","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/katrina_goes12_big.jpg","width":1919,"height":1198,"caption":"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia."},{"@type":"BreadcrumbList","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/conmovedor\/cocinan-mas-de-1000-comidas-para-las-victimas-del-huracan-pero-nadie-habla-de-ello-una-entrada-cambia-la-historia#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.murcianoticias.es\/curiosidades\/"},{"@type":"ListItem","position":2,"name":"Cocinan m\u00e1s de 1000 comidas para las v\u00edctimas del hurac\u00e1n, pero nadie habla de ello: una entrada cambia la historia."}]},{"@type":"WebSite","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website","url":"https:\/\/www.murcianoticias.es\/curiosidades\/","name":"Curiosidades y temas virales","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961","name":"curioso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","caption":"curioso"},"url":"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso"}]}},"_links":{"self":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2745"}],"collection":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/comments?post=2745"}],"version-history":[{"count":0,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media\/2750"}],"wp:attachment":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media?parent=2745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/categories?post=2745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/tags?post=2745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}