{"id":2769,"date":"2019-05-06T19:28:41","date_gmt":"2019-05-06T19:28:41","guid":{"rendered":"https:\/\/murcianoticias.es\/curiosidades\/?p=2769"},"modified":"2020-10-08T23:22:35","modified_gmt":"2020-10-08T23:22:35","slug":"el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes","status":"publish","type":"post","link":"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes","title":{"rendered":"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes."},"content":{"rendered":"<h3>El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes.<\/h3>\n<p>El dentista social de G\u00e9nova tambi\u00e9n explica a los periodistas que lo entrevistaron las razones de la lista de precios que public\u00f3 en su oficina. El cirujano Nicolas Dessypris, de hecho, para ayudar a las personas con problemas dentales requiere una cuota proporcional a las posibilidades de sus pacientes y gracias a esta iniciativa se est\u00e1 hablando mucho de s\u00ed mismo.<\/p>\n<p><img decoding=\"async\" class=\"mb5 sharemeagain\" src=\"https:\/\/img.wtvideo.com\/images\/article\/list\/13382_1.jpg\" \/><\/p>\n<p>\u00abLes quito el dolor de muelas a los que lo tienen.<\/p>\n<p>El Dr. Dessypris, que lleva m\u00e1s de veinticinco a\u00f1os trabajando, se ha unido a una iniciativa promovida con el advenimiento de la crisis econ\u00f3mica por Andi, Oci y el Ministerio de Trabajo, Salud y Pol\u00edticas Sociales y gracias a ella desde 2009 fuera de la oficina se pueden leer las palabras \u00abdentista social\u00bb.<br \/>\nEn lugar de los cl\u00e1sicos, y a menudo inaccesibles, precios de la pr\u00e1ctica dental, en su consultorio cerca del puerto de G\u00e9nova los pacientes pagan en funci\u00f3n de los ingresos: desde el 10% de descuento a los que ganan menos de 20.000 euros al a\u00f1o hasta el 50% (y m\u00e1s) para los que no llegan a los 5.000 \u20ac.<br \/>\nSu trabajo se dirige a todas aquellas categor\u00edas de personas que simplemente no pueden permitirse pagar tres ceros para que les traten los dientes, principalmente pensionistas, desempleados y estudiantes. \u00abDesde que exhib\u00ed el letrero afuera, el n\u00famero de personas en dificultad que acuden a m\u00ed para recibir tratamiento ha aumentado, en promedio dos veces por semana, y casi todas son italianas.<\/p>\n<p>Las cl\u00ednicas dentales que se han unido a esta \u00fatil iniciativa hasta ahora son m\u00e1s de cuatro mil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes. El dentista social de G\u00e9nova tambi\u00e9n explica a los periodistas que lo entrevistaron las razones de la lista de precios que public\u00f3 en su oficina. El cirujano Nicolas Dessypris, de hecho, para ayudar a las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2771,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[794],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes.<\/title>\n<meta name=\"description\" content=\"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes. El dentista social de G\u00e9nova tambi\u00e9n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes.\" \/>\n<meta property=\"og:description\" content=\"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes. El dentista social de G\u00e9nova tambi\u00e9n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes\" \/>\n<meta property=\"og:site_name\" content=\"Curiosidades y temas virales\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/curiosidadesTv1\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-06T19:28:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-08T23:22:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/dentista2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"curioso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"curioso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes\",\"name\":\"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes.\",\"isPartOf\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/dentista2.jpg\",\"datePublished\":\"2019-05-06T19:28:41+00:00\",\"dateModified\":\"2020-10-08T23:22:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\"},\"description\":\"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes. El dentista social de G\u00e9nova tambi\u00e9n\",\"breadcrumb\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes#primaryimage\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/dentista2.jpg\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/dentista2.jpg\",\"width\":1200,\"height\":800,\"caption\":\"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\",\"name\":\"Curiosidades y temas virales\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\",\"name\":\"curioso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"caption\":\"curioso\"},\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes.","description":"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes. El dentista social de G\u00e9nova tambi\u00e9n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes","og_locale":"es_ES","og_type":"article","og_title":"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes.","og_description":"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes. El dentista social de G\u00e9nova tambi\u00e9n","og_url":"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes","og_site_name":"Curiosidades y temas virales","article_publisher":"https:\/\/www.facebook.com\/curiosidadesTv1","article_published_time":"2019-05-06T19:28:41+00:00","article_modified_time":"2020-10-08T23:22:35+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/dentista2.jpg","type":"image\/jpeg"}],"author":"curioso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"curioso","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes","url":"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes","name":"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes.","isPartOf":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes#primaryimage"},"image":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes#primaryimage"},"thumbnailUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/dentista2.jpg","datePublished":"2019-05-06T19:28:41+00:00","dateModified":"2020-10-08T23:22:35+00:00","author":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961"},"description":"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes. El dentista social de G\u00e9nova tambi\u00e9n","breadcrumb":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes#primaryimage","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/dentista2.jpg","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/dentista2.jpg","width":1200,"height":800,"caption":"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes."},{"@type":"BreadcrumbList","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/curiosidades\/el-dentista-que-trata-los-dientes-de-los-que-tienen-dificultades-la-tarifa-depende-de-los-ingresos-de-los-pacientes#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.murcianoticias.es\/curiosidades\/"},{"@type":"ListItem","position":2,"name":"El dentista que trata los dientes de los que tienen dificultades: la tarifa depende de los ingresos de los pacientes."}]},{"@type":"WebSite","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website","url":"https:\/\/www.murcianoticias.es\/curiosidades\/","name":"Curiosidades y temas virales","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961","name":"curioso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","caption":"curioso"},"url":"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso"}]}},"_links":{"self":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2769"}],"collection":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/comments?post=2769"}],"version-history":[{"count":0,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media\/2771"}],"wp:attachment":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media?parent=2769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/categories?post=2769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/tags?post=2769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}