{"id":2824,"date":"2019-05-08T00:57:04","date_gmt":"2019-05-08T00:57:04","guid":{"rendered":"https:\/\/murcianoticias.es\/curiosidades\/?p=2824"},"modified":"2020-10-08T01:45:08","modified_gmt":"2020-10-08T01:45:08","slug":"juego-de-tronos-t8-podria-haber-otros-dragones-teorias","status":"publish","type":"post","link":"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias","title":{"rendered":"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas"},"content":{"rendered":"<h3>Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas<\/h3>\n<p>\u00bfEs Drogon el \u00faltimo de su especie? Seg\u00fan los fans de Game of Thrones, no. En la red hay varias teor\u00edas sugerentes y a veces locas que afirman que puede haber otros dragones&#8230;.<\/p>\n<p>S\u00f3lo hay dos citas (!) para el final de Juego de Tronos, pero es virtualmente imposible predecir d\u00f3nde ir\u00e1 la serie basada en las Cr\u00f3nicas de Hielo y Fuego. Episodio 8&#215;03, La Larga Noche, ha pulverizado la mayor\u00eda de las teor\u00edas de los fan\u00e1ticos sobre lo que podr\u00eda haber pasado y el mareo y el bombo van de la mano.<\/p>\n<p>&nbsp;<\/p>\n<p>Por otro lado, el giro que han tomado los acontecimientos de The Last of the Starks, la \u00faltima promoci\u00f3n y la presencia del (gran) especialista en batallas, Miguel Sapochnik, al frente de los pr\u00f3ximos 80 minutos anuncian un nuevo y \u00e9pico choque.<\/p>\n<p>Pero, \u00bfest\u00e1 Daenerys preparado para el enfrentamiento final con Cersei? El ej\u00e9rcito de Khaleesi ha sido reducido a m\u00e1s de la mitad por el ej\u00e9rcito del Rey Nocturno y la Reina del Desembarco del Rey puede contar con la flota de Euron Greyjoy y los 20.000 hombres y 2.000 caballos de la Compa\u00f1\u00eda Dorada.<\/p>\n<h3>\u00a1Atenci\u00f3n! \u00a1Posibles <strong>spoiler!<\/strong><\/h3>\n<p>Sobre todo, la Madre de los Dragones permaneci\u00f3 con s\u00f3lo uno de sus queridos hijos. Drogon es el \u00faltimo superviviente y es tan vulnerable como Rhaegal. El poder de fuego de Young Targaryen (literalmente) est\u00e1 en su punto m\u00e1s bajo y sus posibilidades de ganar el Trono de Hierro y vengarse de Cersei parecen muy bajas.<\/p>\n<p>Menos que un giro sensacional.<\/p>\n<p>Diversas teor\u00edas circulan por la red sobre la posible existencia de otros dragones. Las m\u00e1s interesantes han sido recogidas por Time y Refinery29 y abren el camino a diferentes escenarios.<\/p>\n<p>Drogon ha puesto huevos<br \/>\nDaenerys llam\u00f3 a sus dragones Drogon, Rhaegal y Viserion, en homenaje a su marido Khal Drogo y a sus hermanos Rhaegar y Viserys. Pero los nombres masculinos no deben ser enga\u00f1ados. En las novelas de George R. R. Martin se explica que las poderosas criaturas aladas no son \u00abni masculinas ni femeninas\u00bb, sino \u00abcambiantes como la llama\u00bb. Esto significa que Drogon puede haber puesto huevos. Pero \u00bfpor qu\u00e9 \u00e9l\/ella?<\/p>\n<p>Durante la quinta temporada de Game of Thrones, el hijo favorito de Khaleesi desaparece por mucho tiempo y su propia madre no sabe d\u00f3nde termin\u00f3.<\/p>\n<p>El misterio se revela en el episodio 5&#215;05, Kill the Boy. Tyrion y Ser Jorah Mormont est\u00e1n navegando en un peque\u00f1o barco por el r\u00edo que cruza las ruinas de la antigua Valyria, cuando el duende ve en el cielo al Drogon.<\/p>\n<h3>\u00bfQu\u00e9 hace el drag\u00f3n en las tierras ancestrales de los Targaryen?<\/h3>\n<p>Una hip\u00f3tesis es que puso huevos y cuid\u00f3 a sus hijos hasta el destete. Pero tambi\u00e9n puede ser que ya haya encontrado otros adultos similares (lo que no excluye a los primeros).<\/p>\n<p>Se puede ver c\u00f3mo una u otra posibilidad (o ambas) pueden jugar a favor de Khaleesi. Pero es cierto que Drogon ha mostrado una actitud protectora hacia Daenerys en varias ocasiones. El m\u00e1s reciente fue despu\u00e9s de la batalla con el Rey Nocturno, cuando se acurruc\u00f3 junto a su madre llorando por el cuerpo de Ser Jorah Mormont y se apret\u00f3 en una especie de abrazo con su cuerpo y sus alas.<\/p>\n<p>Si varios dragones atacaron la capital, los escorpiones de Qyburn podr\u00edan no ser suficientes.<\/p>\n<p>Y sobre esta eventualidad, el escritor tiene una pregunta. \u00bfQu\u00e9 ve Euron Greyjoy cuando mira al final del teaser de 8&#215;05? El Rey de las Islas del Hierro cambia su expresi\u00f3n y parece molesto (a partir del minuto 00:28). Teniendo en cuenta que ya ha matado a un drag\u00f3n (cuando hab\u00eda dos), la sola visi\u00f3n de Drogon no deber\u00eda molestarle de esa manera&#8230;.<\/p>\n<p>Los 3 huevos de los dragones de Daenerys no fueron los \u00faltimos<br \/>\nLos huevos de drag\u00f3n de los que nacen Drogon, Rhaegal y Viserion aparecen en el episodio de Game of Thrones 1&#215;01, Winter is Coming, cuando el magistrado Illyrio Mopatis se los entrega a Daenerys con motivo de su boda con Khal Drogo:<\/p>\n<p>\u00abHuevos de drag\u00f3n, Daenerys. Desde la Tierra de las Sombras, m\u00e1s all\u00e1 de Asshai. El paso de las edades las ha transformado en piedra, pero siempre son maravillosos\u00bb.<\/p>\n<p>El aliado de Varys y anfitri\u00f3n de Daenerys y su hermano Viserys en Pentos sugiere que este es un regalo muy valioso, porque es \u00fanico en su tipo. \u00bfPero es realmente as\u00ed? \u00bfY si hubiera otros huevos de drag\u00f3n en la Tierra de las Sombras? Despu\u00e9s de todo, estos son lugares m\u00e1gicos y misteriosos.<\/p>\n<h3>Pero quiz\u00e1s podr\u00eda haber espec\u00edmenes mucho m\u00e1s cerca.<\/h3>\n<p>Como recordaba hace tiempo un usuario de la plataforma Medium, en el libro The World of Ice and Fire. La historia oficial de Westeros y el Trono de George R. R. Martin, es contada por la historia del enano loco Mushroom, quien afirma que el drag\u00f3n Vermax ha puesto huevos en las criptas de Invernalia.<\/p>\n<p>Ambas teor\u00edas son fascinantes, pero&#8230; de poca utilidad. Al menos, desde el punto de vista de Daenerys.<\/p>\n<p>Si la posible existencia de huevos garantiza un futuro al linaje de los dragones, ciertamente no ayuda a Khaleesi en el futuro inmediato. Incluso si los j\u00f3venes Targaryen encontraban la manera de abrir una cr\u00eda, los reci\u00e9n nacidos tardaban a\u00f1os en crecer.<\/p>\n<h3>Rhaegal no est\u00e1 realmente muerto.<\/h3>\n<p>Rhaegal fue atravesado por numerosas jabalinas lanzadas por los Escorpiones montados en los barcos de Euron Greyjoy y se hundi\u00f3 en las profundidades del mar perdiendo el derramamiento de sangre. Su muerte parecer\u00eda imposible, pero&#8230; no todos los aficionados est\u00e1n convencidos de ello.<\/p>\n<p>Seg\u00fan una teor\u00eda que circula por la red, el drag\u00f3n podr\u00eda regresar.<\/p>\n<p>Adem\u00e1s de la ya mencionada expresi\u00f3n de angustia de Euron, los partidarios de la hip\u00f3tesis (loca, pero fascinante) llevan como pista el di\u00e1logo entre Cersei y el Rey de las Islas de Hierro despu\u00e9s de la emboscada a la flota Targaryen. La Reina del Desembarco del Rey pregunta a su amante si est\u00e1 \u00abseguro\u00bb de la muerte de Rhaegal y Euron responde que lo ha visto hundirse en las olas. Pero cuando un personaje es sincero sobre una muerte y no hay cuerpo&#8230; normalmente, el giro nos golpea.<\/p>\n<p>Por otro lado, el comentario de los guionistas al episodio parece excluir la supervivencia del drag\u00f3n. D. B. Weiss y David Benioff explicaron que la muerte de Rhaegal tendr\u00e1 graves repercusiones en Daenerys. Pero para lo irreductible, tambi\u00e9n es cierto que los dos escritores hab\u00edan dicho y reiterado que Jon Snow no volver\u00eda.<\/p>\n<p>En definitiva, como siempre a la espera del nuevo episodio de Game of Thrones, vale todo y lo contrario de todo.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/lc2hvst1dbs\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas \u00bfEs Drogon el \u00faltimo de su especie? Seg\u00fan los fans de Game of Thrones, no. En la red hay varias teor\u00edas sugerentes y a veces locas que afirman que puede haber otros dragones&#8230;. S\u00f3lo hay dos citas (!) para el final de Juego de Tronos, pero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2825,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[783],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas<\/title>\n<meta name=\"description\" content=\"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas \u00bfEs Drogon el \u00faltimo de su especie? Seg\u00fan los fans de Game of Thrones, no. En la red hay varias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas\" \/>\n<meta property=\"og:description\" content=\"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas \u00bfEs Drogon el \u00faltimo de su especie? Seg\u00fan los fans de Game of Thrones, no. En la red hay varias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias\" \/>\n<meta property=\"og:site_name\" content=\"Curiosidades y temas virales\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/curiosidadesTv1\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-08T00:57:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-08T01:45:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/juego-de-tronos-from-software.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"curioso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"curioso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias\",\"name\":\"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas\",\"isPartOf\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/juego-de-tronos-from-software.jpg\",\"datePublished\":\"2019-05-08T00:57:04+00:00\",\"dateModified\":\"2020-10-08T01:45:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\"},\"description\":\"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas \u00bfEs Drogon el \u00faltimo de su especie? Seg\u00fan los fans de Game of Thrones, no. En la red hay varias\",\"breadcrumb\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias#primaryimage\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/juego-de-tronos-from-software.jpg\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/juego-de-tronos-from-software.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\",\"name\":\"Curiosidades y temas virales\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\",\"name\":\"curioso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"caption\":\"curioso\"},\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas","description":"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas \u00bfEs Drogon el \u00faltimo de su especie? Seg\u00fan los fans de Game of Thrones, no. En la red hay varias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias","og_locale":"es_ES","og_type":"article","og_title":"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas","og_description":"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas \u00bfEs Drogon el \u00faltimo de su especie? Seg\u00fan los fans de Game of Thrones, no. En la red hay varias","og_url":"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias","og_site_name":"Curiosidades y temas virales","article_publisher":"https:\/\/www.facebook.com\/curiosidadesTv1","article_published_time":"2019-05-08T00:57:04+00:00","article_modified_time":"2020-10-08T01:45:08+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/juego-de-tronos-from-software.jpg","type":"image\/jpeg"}],"author":"curioso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"curioso","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias","url":"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias","name":"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas","isPartOf":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias#primaryimage"},"image":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias#primaryimage"},"thumbnailUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/juego-de-tronos-from-software.jpg","datePublished":"2019-05-08T00:57:04+00:00","dateModified":"2020-10-08T01:45:08+00:00","author":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961"},"description":"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas \u00bfEs Drogon el \u00faltimo de su especie? Seg\u00fan los fans de Game of Thrones, no. En la red hay varias","breadcrumb":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias#primaryimage","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/juego-de-tronos-from-software.jpg","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/juego-de-tronos-from-software.jpg","width":1280,"height":720,"caption":"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/series\/juego-de-tronos-t8-podria-haber-otros-dragones-teorias#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.murcianoticias.es\/curiosidades\/"},{"@type":"ListItem","position":2,"name":"Juego de Tronos T8: \u00bfPodr\u00eda haber otros dragones? Teor\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website","url":"https:\/\/www.murcianoticias.es\/curiosidades\/","name":"Curiosidades y temas virales","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961","name":"curioso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","caption":"curioso"},"url":"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso"}]}},"_links":{"self":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2824"}],"collection":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/comments?post=2824"}],"version-history":[{"count":0,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media\/2825"}],"wp:attachment":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media?parent=2824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/categories?post=2824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/tags?post=2824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}