{"id":2828,"date":"2019-05-08T18:52:44","date_gmt":"2019-05-08T18:52:44","guid":{"rendered":"https:\/\/murcianoticias.es\/curiosidades\/?p=2828"},"modified":"2020-10-15T00:59:14","modified_gmt":"2020-10-15T00:59:14","slug":"entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees","status":"publish","type":"post","link":"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees","title":{"rendered":"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees."},"content":{"rendered":"<h3>Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees.<\/h3>\n<p>El regreso de las 6 Gemas del Infinito, una posible alternativa temporal, cara a cara con el enemigo del pasado: la misi\u00f3n del Capit\u00e1n Am\u00e9rica en Avengers: Endgame.<\/p>\n<p>La extra\u00f1eza de Avengers: Endgame reside en el hecho de que ha canalizado la mayor atenci\u00f3n de los espectadores al destino de sus h\u00e9roes. Hay quienes se han sacrificado (m\u00e1s de uno) y quienes, por una vez, han dejado de lado el altruismo y la responsabilidad y han disfrutado un poco de esa vida que por una raz\u00f3n u otra siempre ha sido negada.<\/p>\n<p>La pel\u00edcula de Anthony y Joe Russo, sin embargo, a la vez que distrae con un masturbador y desgarrador juego de cuentas entre los Vengadores y Thanos, ha puesto en escena algunos topoi evocadores del cine de ciencia ficci\u00f3n, especialmente el viaje a trav\u00e9s del tiempo, que en la secuela de la Guerra del Infinito ha asumido un valor inconfundiblemente metacinematogr\u00e1fico, si no auto-celebrante.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2829 size-large\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-ironman-1280x1024.jpg\" alt=\"\" width=\"1000\" height=\"800\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-ironman.jpg 1280w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-ironman-300x240.jpg 300w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-ironman-768x614.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Endgame, en la pr\u00e1ctica, se abre a diferentes puntos de reflexi\u00f3n y hace posibles escenarios futuros hasta ahora inimaginables, aline\u00e1ndose esencialmente con el modus operandi de los c\u00f3mics de Marvel, en los que las sagas suelen seguir diferentes l\u00edneas temporales, distorsionando lo narrado anteriormente. En el caso del \u00faltimo crossover sobre los superh\u00e9roes m\u00e1s fuertes de la Tierra (y no s\u00f3lo), el debate se ha centrado hasta ahora en las l\u00edneas de tiempo alternativas generadas por los torpes intentos de volver al pasado de los distintos Stark, Rogers y Nebula. Hay un aspecto, sin embargo, que la pel\u00edcula eligi\u00f3 no mostrar: el regreso de las Gemas del Infinito. \u00bfEstamos seguros de que fue un paseo para volver a colocarlos en su lugar en la ventana de tiempo correcta?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2831 size-large\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1-1280x720.jpg\" alt=\"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees.\" width=\"1000\" height=\"563\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1.jpg 1280w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1-300x169.jpg 300w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1-768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<h3>Avengers: Endgame, la \u00faltima misi\u00f3n de Steve Rogers<\/h3>\n<p>En el final de Avengers: Endgame, un anciano Steve Rogers regresa al presente despu\u00e9s de vivir toda una vida junto a su amada Peggy Carter. Misi\u00f3n cumplida por el Capit\u00e1n, que ha reposicionado as\u00ed las Gemas del Infinito en el punto correcto de la historia, evitando en teor\u00eda la proliferaci\u00f3n de l\u00edneas de tiempo alternativas a la principal. Sin embargo, persiste la duda. En primer lugar, \u00bfqu\u00e9 hay de Loki y Tesseract, que desaparecieron de la escena en 2012, justo despu\u00e9s de la batalla de Nueva York ganada por los Vengadores en su debut como un equipo de superh\u00e9roes? Una realidad no relacionada con la principal es una posibilidad que el Universo Cinematogr\u00e1fico Marvel ciertamente deja abierta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2830 size-large\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/Endgame-22-1280x524.jpg\" alt=\"\" width=\"1000\" height=\"409\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/Endgame-22-1280x524.jpg 1280w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/Endgame-22-300x123.jpg 300w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/Endgame-22-768x315.jpg 768w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/Endgame-22.jpg 1538w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Las Gemas originales, como saben, fueron destruidas por Thanos inmediatamente despu\u00e9s del estallido de la Guerra del Infinito. Un gesto extremo que casi le cuesta la vida al tit\u00e1n, luego decapitado sin piedad por Thor. Las gemas recuperadas por los Vengadores y utilizadas en el dram\u00e1tico \u00absnap\u00bb final de Tony Stark, sin embargo, en los \u00faltimos minutos de la pel\u00edcula se conf\u00edan al Capit\u00e1n Am\u00e9rica la tarea de reposicionarlas en el lugar y momento adecuados.<\/p>\n<p>Y Cap sin duda completa la delicada operaci\u00f3n espacio-tiempo. La curiosidad, sin embargo, no es tanto el \u00abcu\u00e1ndo\u00bb o el \u00abd\u00f3nde\u00bb como el \u00abc\u00f3mo\u00bb. \u00bfAlguna vez te has preguntado c\u00f3mo los corrigi\u00f3? \u00bfC\u00f3mo lo hizo? Si para algunas de las reliquias la tarea fue bastante f\u00e1cil, para algunas Gemas no debe haber sido un regreso sin dificultad o dificultad&#8230;.. verg\u00fcenza.<\/p>\n<h3>Vengadores: Final del juego, la restituci\u00f3n de las 6 Gemas del Infinito<\/h3>\n<p>Tomemos la llamada. Gema del Tiempo: regres\u00f3 al Antiguo (Tilda Swinton). Tan f\u00e1cil como enviar una vocal en WhatsApp. Gema de la Mente: el mismo discurso que el del Tiempo, fue suficiente para volver a los acontecimientos de Los Vengadores. Para el Teseracto, la Gema Espacial, por otro lado, se trataba de volver a violar una base militar americana en los a\u00f1os 70, esta vez sin la compa\u00f1\u00eda de \u00abHoward Potts\u00bb. Gema de Poder, el Orbe: reposicionado como Indiana Jones en el templo, con una divertida resucitaci\u00f3n a un d\u00e9bil Se\u00f1or de las Estrellas (traicionado por War Machine).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2832 size-full\" src=\"https:\/\/murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame3.jpg\" alt=\"\" width=\"1214\" height=\"697\" srcset=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame3.jpg 1214w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame3-300x172.jpg 300w, https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame3-768x441.jpg 768w\" sizes=\"(max-width: 1214px) 100vw, 1214px\" \/><\/p>\n<p>Las otras dos Gemas, la Realidad y el Alma, requer\u00edan una operaci\u00f3n mucho m\u00e1s compleja: Nadie pregunt\u00f3 c\u00f3mo se las arregl\u00f3 Cap para reposicionar el Aether? \u00bfUn disparo a Jane Foster no sin una pizca de verg\u00fcenza? Tal vez, tal vez inmediatamente despu\u00e9s de devolver el Mjolnir a un irrespetuoso &#8211; y todav\u00eda t\u00f3nico &#8211; Thor. En cuanto a la Gema del Alma, debe haber sido un verdadero shock para Steve Rogers devolverla: ir a Vormir y encontrarse cara a cara con Red Skull, un antiguo archienemigo. Adem\u00e1s, aunque muchos esperaban, el regreso de la Gema no pod\u00eda significar el regreso a la vida de la Viuda Negra. Se repite tanto por el Guardi\u00e1n como por el Ojo de Halc\u00f3n en Endgame: es un intercambio eterno, un regalo por un regalo, irrevocable.<\/p>\n<p>As\u00ed que, a excepci\u00f3n del Teseracto robado por Loki en 2012, las Gemas han regresado a su lugar, y podr\u00edan ser reutilizadas m\u00e1s tarde. Simplemente aproveche la tecnolog\u00eda se\u00f1alada por Hank Pym y perfeccionada por Tony Stark. Un juego de ni\u00f1os. Casi.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/G7EWTx_hG-s\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees. El regreso de las 6 Gemas del Infinito, una posible alternativa temporal, cara a cara con el enemigo del pasado: la misi\u00f3n del Capit\u00e1n Am\u00e9rica en Avengers: Endgame. La extra\u00f1eza de Avengers: Endgame reside en el hecho [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[776],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees.<\/title>\n<meta name=\"description\" content=\"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees. El regreso de las 6 Gemas del Infinito, una posible\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees.\" \/>\n<meta property=\"og:description\" content=\"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees. El regreso de las 6 Gemas del Infinito, una posible\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees\" \/>\n<meta property=\"og:site_name\" content=\"Curiosidades y temas virales\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/curiosidadesTv1\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-08T18:52:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-15T00:59:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"curioso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"curioso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees\",\"name\":\"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees.\",\"isPartOf\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1.jpg\",\"datePublished\":\"2019-05-08T18:52:44+00:00\",\"dateModified\":\"2020-10-15T00:59:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\"},\"description\":\"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees. El regreso de las 6 Gemas del Infinito, una posible\",\"breadcrumb\":{\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees#primaryimage\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1.jpg\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#website\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/\",\"name\":\"Curiosidades y temas virales\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961\",\"name\":\"curioso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"contentUrl\":\"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959\",\"caption\":\"curioso\"},\"url\":\"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees.","description":"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees. El regreso de las 6 Gemas del Infinito, una posible","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees","og_locale":"es_ES","og_type":"article","og_title":"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees.","og_description":"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees. El regreso de las 6 Gemas del Infinito, una posible","og_url":"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees","og_site_name":"Curiosidades y temas virales","article_publisher":"https:\/\/www.facebook.com\/curiosidadesTv1","article_published_time":"2019-05-08T18:52:44+00:00","article_modified_time":"2020-10-15T00:59:14+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1.jpg","type":"image\/jpeg"}],"author":"curioso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"curioso","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees","url":"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees","name":"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees.","isPartOf":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees#primaryimage"},"image":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees#primaryimage"},"thumbnailUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1.jpg","datePublished":"2019-05-08T18:52:44+00:00","dateModified":"2020-10-15T00:59:14+00:00","author":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961"},"description":"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees. El regreso de las 6 Gemas del Infinito, una posible","breadcrumb":{"@id":"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees#primaryimage","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1.jpg","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/uploads\/2019\/05\/endgame-2-1.jpg","width":1280,"height":720,"caption":"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees."},{"@type":"BreadcrumbList","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/peliculas\/entrega-de-las-joyas-del-infinito-despues-de-los-vengadores-endgame-no-ha-sido-tan-facil-como-crees#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.murcianoticias.es\/curiosidades\/"},{"@type":"ListItem","position":2,"name":"Entrega de las joyas del infinito despu\u00e9s de los Vengadores: Endgame no ha sido tan f\u00e1cil como crees."}]},{"@type":"WebSite","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#website","url":"https:\/\/www.murcianoticias.es\/curiosidades\/","name":"Curiosidades y temas virales","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.murcianoticias.es\/curiosidades\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/593d3ffdf4aca4f02b8f37f502a5d961","name":"curioso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.murcianoticias.es\/curiosidades\/#\/schema\/person\/image\/","url":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","contentUrl":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-content\/litespeed\/avatar\/3ab1418699a7bcf69b9b386c43975492.jpg?ver=1783648959","caption":"curioso"},"url":"https:\/\/www.murcianoticias.es\/curiosidades\/author\/curioso"}]}},"_links":{"self":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2828"}],"collection":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/comments?post=2828"}],"version-history":[{"count":0,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/posts\/2828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media\/2831"}],"wp:attachment":[{"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/media?parent=2828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/categories?post=2828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.murcianoticias.es\/curiosidades\/wp-json\/wp\/v2\/tags?post=2828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}